{"id":48,"count":16,"description":"Desde elegantes colgantes de perla hasta cl\u00e1sicos collares y dise\u00f1os m\u00e1s llamativos, descubre piezas que combinan la belleza atemporal con un estilo contempor\u00e1neo.","link":"https:\/\/www.tenerifeperla.com\/es\/categoria-producto\/collares-de-perlas\/","name":"Collares de Perlas","slug":"collares-de-perlas","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/www.tenerifeperla.com\/es\/wp-json\/wp\/v2\/product_cat\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tenerifeperla.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.tenerifeperla.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.tenerifeperla.com\/es\/wp-json\/wp\/v2\/product?product_cat=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}